{"id":15217,"date":"2020-12-31T09:19:24","date_gmt":"2020-12-31T08:19:24","guid":{"rendered":"http:\/\/enricomaciasloriental.fr\/WordPress\/?p=15217"},"modified":"2020-12-31T09:19:26","modified_gmt":"2020-12-31T08:19:26","slug":"sezer-guvenirgil-yillar-almaz-uste-verir-1982","status":"publish","type":"post","link":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/","title":{"rendered":"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 )"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?v=p895jo_WITk\n<\/div><figcaption>Toutes mes chansons  &#8211; Enrico Macias (1980) <br \/>Reprise de Sezer G\u00fcvenirgil<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":36,"featured_media":15219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-15217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interpretes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 ) - ENRICO MACIAS L&#039;Oriental<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 ) - ENRICO MACIAS L&#039;Oriental\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/\" \/>\n<meta property=\"og:site_name\" content=\"ENRICO MACIAS L&#039;Oriental\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-31T08:19:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-31T08:19:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2020\/12\/Capture-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"968\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Loriental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Loriental\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/\"},\"author\":{\"name\":\"Loriental\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#\\\/schema\\\/person\\\/53fba112c6f4f0b335578890a816262e\"},\"headline\":\"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 )\",\"datePublished\":\"2020-12-31T08:19:24+00:00\",\"dateModified\":\"2020-12-31T08:19:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/\"},\"wordCount\":28,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#\\\/schema\\\/person\\\/53fba112c6f4f0b335578890a816262e\"},\"image\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2020\\\/12\\\/Capture-2.jpg\",\"articleSection\":[\"Interpr\u00e8tes\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/\",\"url\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/\",\"name\":\"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 ) - ENRICO MACIAS L&#039;Oriental\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2020\\\/12\\\/Capture-2.jpg\",\"datePublished\":\"2020-12-31T08:19:24+00:00\",\"dateModified\":\"2020-12-31T08:19:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/#primaryimage\",\"url\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2020\\\/12\\\/Capture-2.jpg\",\"contentUrl\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2020\\\/12\\\/Capture-2.jpg\",\"width\":968,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 )\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#website\",\"url\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/\",\"name\":\"ENRICO MACIAS L'Oriental\",\"description\":\"IL EST COMME LE SOLEIL\",\"publisher\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#\\\/schema\\\/person\\\/53fba112c6f4f0b335578890a816262e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#\\\/schema\\\/person\\\/53fba112c6f4f0b335578890a816262e\",\"name\":\"Loriental\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2015\\\/02\\\/cropped-bannier_altaiir-enrico.jpg\",\"url\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2015\\\/02\\\/cropped-bannier_altaiir-enrico.jpg\",\"contentUrl\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2015\\\/02\\\/cropped-bannier_altaiir-enrico.jpg\",\"width\":1200,\"height\":150,\"caption\":\"Loriental\"},\"logo\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2015\\\/02\\\/cropped-bannier_altaiir-enrico.jpg\"},\"sameAs\":[\"http:\\\/\\\/www.enricomaciasloriental.fr\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 ) - ENRICO MACIAS L&#039;Oriental","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/","og_locale":"fr_FR","og_type":"article","og_title":"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 ) - ENRICO MACIAS L&#039;Oriental","og_url":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/","og_site_name":"ENRICO MACIAS L&#039;Oriental","article_published_time":"2020-12-31T08:19:24+00:00","article_modified_time":"2020-12-31T08:19:26+00:00","og_image":[{"width":968,"height":540,"url":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2020\/12\/Capture-2.jpg","type":"image\/jpeg"}],"author":"Loriental","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Loriental"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/#article","isPartOf":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/"},"author":{"name":"Loriental","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#\/schema\/person\/53fba112c6f4f0b335578890a816262e"},"headline":"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 )","datePublished":"2020-12-31T08:19:24+00:00","dateModified":"2020-12-31T08:19:26+00:00","mainEntityOfPage":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/"},"wordCount":28,"commentCount":0,"publisher":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#\/schema\/person\/53fba112c6f4f0b335578890a816262e"},"image":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/#primaryimage"},"thumbnailUrl":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2020\/12\/Capture-2.jpg","articleSection":["Interpr\u00e8tes"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/","url":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/","name":"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 ) - ENRICO MACIAS L&#039;Oriental","isPartOf":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/#primaryimage"},"image":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/#primaryimage"},"thumbnailUrl":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2020\/12\/Capture-2.jpg","datePublished":"2020-12-31T08:19:24+00:00","dateModified":"2020-12-31T08:19:26+00:00","breadcrumb":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/#primaryimage","url":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2020\/12\/Capture-2.jpg","contentUrl":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2020\/12\/Capture-2.jpg","width":968,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/sezer-guvenirgil-yillar-almaz-uste-verir-1982\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/enricomaciasloriental.fr\/WordPress\/"},{"@type":"ListItem","position":2,"name":"Sezer G\u00fcvenirgil | Y\u0131llar Almaz \u00dcste verir ( 1982 )"}]},{"@type":"WebSite","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#website","url":"https:\/\/enricomaciasloriental.fr\/WordPress\/","name":"ENRICO MACIAS L'Oriental","description":"IL EST COMME LE SOLEIL","publisher":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#\/schema\/person\/53fba112c6f4f0b335578890a816262e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enricomaciasloriental.fr\/WordPress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#\/schema\/person\/53fba112c6f4f0b335578890a816262e","name":"Loriental","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2015\/02\/cropped-bannier_altaiir-enrico.jpg","url":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2015\/02\/cropped-bannier_altaiir-enrico.jpg","contentUrl":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2015\/02\/cropped-bannier_altaiir-enrico.jpg","width":1200,"height":150,"caption":"Loriental"},"logo":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2015\/02\/cropped-bannier_altaiir-enrico.jpg"},"sameAs":["http:\/\/www.enricomaciasloriental.fr\/"]}]}},"featured_image_src":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2020\/12\/Capture-2.jpg","featured_image_src_square":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2020\/12\/Capture-2.jpg","author_info":{"display_name":"Loriental","author_link":"https:\/\/enricomaciasloriental.fr\/WordPress\/author\/admin9234\/"},"rbea_author_info":{"display_name":"Loriental","author_link":"https:\/\/enricomaciasloriental.fr\/WordPress\/author\/admin9234\/"},"rbea_excerpt_info":null,"category_list":"<a href=\"https:\/\/enricomaciasloriental.fr\/WordPress\/category\/videos\/interpretes\/\">Interpr\u00e8tes<\/a>","comments_num":"0 comments","_links":{"self":[{"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/posts\/15217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/comments?post=15217"}],"version-history":[{"count":0,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/posts\/15217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/media\/15219"}],"wp:attachment":[{"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/media?parent=15217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/categories?post=15217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/tags?post=15217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}