{"id":9883,"date":"2016-08-21T10:46:43","date_gmt":"2016-08-21T08:46:43","guid":{"rendered":"http:\/\/enricomaciasloriental.fr\/WordPress\/?p=9883"},"modified":"2016-08-21T10:48:18","modified_gmt":"2016-08-21T08:48:18","slug":"enrico-macias-a-la-fete-de-st-privat-a-carmaux","status":"publish","type":"post","link":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/","title":{"rendered":"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux"},"content":{"rendered":"<p><a href=\"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2016\/08\/Carmaux-8344-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-9886\" src=\"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2016\/08\/Carmaux-8344-1-300x200.jpg\" alt=\"Carmaux-8344\" width=\"300\" height=\"200\" srcset=\"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/2016\/08\/Carmaux-8344-1-300x200.jpg 300w, https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/2016\/08\/Carmaux-8344-1-768x512.jpg 768w, https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/2016\/08\/Carmaux-8344-1.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Il faisait chaud, tr\u00e8s chaud ce vendredi 19 aout 2016 \u00e0 Carmaux pour l\u2019ouverture de la F\u00eate de St Privat.<\/p>\n<p>Mais les Carmausins se sont \u00e9vertu\u00e9s toute la journ\u00e9e \u00e0 peaufiner les derniers d\u00e9tails pour que tout soit parfait pour cette premi\u00e8re soir\u00e9e.<\/p>\n<p>Apr\u00e8s la Remise des clefs de la ville \u00e0 la Reine des f\u00eates de St Privat, puis l\u2019ouverture des bodegas \u00e0 19h, c\u2019est \u00e0 Enrico Macias que revenait l\u2019honneur d\u2019ouvrir les festivit\u00e9s dans la salle Fran\u00e7ois Mitterand.<\/p>\n<p>Les mesures de s\u00e9curit\u00e9 renforc\u00e9es ayant entrain\u00e9 une petite demi-heure de retard sur l\u2019horaire pr\u00e9vu, c\u2019est \u00e0 21h30 que les musiciens sont enfin entr\u00e9s sur sc\u00e8ne et que le pr\u00e9sident du COFEST a ouvert officiellement les f\u00eates de St Privat 2016. Puis les lumi\u00e8res se sont \u00e9teintes, guitares, violon, basse, accord\u00e9on, batterie et percussions ont jou\u00e9 les premi\u00e8res notes de l\u2019intro et la magie s\u2019est install\u00e9e avec l\u2019entr\u00e9e en sc\u00e8ne d\u2019Enrico, aminci, bronz\u00e9 et rayonnant qui a pos\u00e9 le d\u00e9cor oriental au c\u0153ur du Tarn aux accents d\u2019un Koum Tara toujours flamboyant.<\/p>\n<p>Il a ensuite exprim\u00e9 tout son plaisir de se trouver \u00e0 Carmaux rappelant qu\u2019il avait fait son premier concert dans cette ville \u00e0 l\u2019\u00e2ge de 23 ans. Bien des ann\u00e9es de succ\u00e8s plus tard, revenu sur les traces de ce premier r\u00e9cital, il a encore une fois enflamm\u00e9 la salle avec ses succ\u00e8s de toujours mais aussi avec des chansons de son nouvel album.<\/p>\n<p>Souriant, blagueur, chaleureux et surtout sinc\u00e8re, il a le don d\u2019\u00e9tablir imm\u00e9diatement le lien avec son public qui le lui rend avec autant de c\u0153ur et de spontan\u00e9it\u00e9. Passant tour \u00e0 tour de la nostalgie de son pays natal, \u00e0 l\u2019\u00e9motion avec \u00ab\u00a0Pour toutes ces raisons, je t\u2019aime\u00a0\u00bb et \u00ab\u00a0Un berger vient de tomber\u00a0\u00bb, il n\u2019oublie jamais la Fraternit\u00e9 et la f\u00eate pour r\u00e9unir tous les c\u0153urs de bonne volont\u00e9. Cette douleur permanente qui est en lui, il sait la d\u00e9passer et se transcender pour combattre encore et toujours pour la Paix et donner la joie au c\u0153ur de ceux qu\u2019il croise.<\/p>\n<p>\u00ab\u00a0Que Dieu vous garde \u00e0 moi\u00a0\u00bb, \u00ab\u00a0Je vous aime\u00a0!\u00a0\u00bb a t\u2019il dit au Carmausins.<\/p>\n<p>\u00ab\u00a0Que Dieu vous garde \u00e0 nous\u00a0\u00bb\u00a0Enrico ! Le soleil de votre amiti\u00e9 redonne \u00e0 nos c\u0153urs un peu de l\u2019espoir qui manque dans notre ciel aujourd\u2019hui.<\/p>\n<p>Merci \u00e0 vous et que \u00e7a dure encore longtemps<\/p>\n<p>Liste des chansons<\/p>\n<p>Koum Tara<br \/>\nAdieu mon pays<br \/>\nLe voyage<br \/>\nAux talons de ses souliers<br \/>\nPour toutes ces raisons je t\u2019aime<br \/>\nLes gens du nord Medley\u00a0: Paris tu m\u2019as pris dans tes bras,<br \/>\nLes millionnaires du dimanche<br \/>\nMon c\u0153ur d\u2019attache<br \/>\nA la gr\u00e2ce de Dieu<br \/>\nAie aie aie je l\u2019aime<br \/>\nUn berger vient de tomber<br \/>\nLes filles de mon pays<br \/>\nSolenzara<br \/>\nAlma del sol (avec Bruno Bongar\u00e7on)<br \/>\nLe violon de mon p\u00e8re<br \/>\nMedley oriental<br \/>\nYa Rayah<br \/>\nLe mendiant de l\u2019amour<br \/>\nOseh Shalom<br \/>\nPorompompero<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il faisait chaud, tr\u00e8s chaud ce vendredi 19 aout 2016 \u00e0 Carmaux pour l\u2019ouverture de la F\u00eate de St Privat. Mais les Carmausins se sont \u00e9vertu\u00e9s toute la journ\u00e9e \u00e0 peaufiner les derniers d\u00e9tails &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"more-link\" href=\"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/\"> <span class=\"screen-reader-text\">Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux<\/span> Read more \u2192<\/a><\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9883","post","type-post","status-publish","format-standard","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux - ENRICO MACIAS L&#039;Oriental<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux - ENRICO MACIAS L&#039;Oriental\" \/>\n<meta property=\"og:description\" content=\"Il faisait chaud, tr\u00e8s chaud ce vendredi 19 aout 2016 \u00e0 Carmaux pour l\u2019ouverture de la F\u00eate de St Privat. Mais les Carmausins se sont \u00e9vertu\u00e9s toute la journ\u00e9e \u00e0 peaufiner les derniers d\u00e9tails &hellip; Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux Read more \u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/\" \/>\n<meta property=\"og:site_name\" content=\"ENRICO MACIAS L&#039;Oriental\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-21T08:46:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-21T08:48:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2016\/08\/Carmaux-8344-1-300x200.jpg\" \/>\n<meta name=\"author\" content=\"Loriental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Loriental\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/\"},\"author\":{\"name\":\"Loriental\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#\\\/schema\\\/person\\\/53fba112c6f4f0b335578890a816262e\"},\"headline\":\"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux\",\"datePublished\":\"2016-08-21T08:46:43+00:00\",\"dateModified\":\"2016-08-21T08:48:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/\"},\"wordCount\":532,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#\\\/schema\\\/person\\\/53fba112c6f4f0b335578890a816262e\"},\"image\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2016\\\/08\\\/Carmaux-8344-1-300x200.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/\",\"url\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/\",\"name\":\"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux - ENRICO MACIAS L&#039;Oriental\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2016\\\/08\\\/Carmaux-8344-1-300x200.jpg\",\"datePublished\":\"2016-08-21T08:46:43+00:00\",\"dateModified\":\"2016-08-21T08:48:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2016\\\/08\\\/Carmaux-8344-1.jpg\",\"contentUrl\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2016\\\/08\\\/Carmaux-8344-1.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#website\",\"url\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/\",\"name\":\"ENRICO MACIAS L'Oriental\",\"description\":\"IL EST COMME LE SOLEIL\",\"publisher\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#\\\/schema\\\/person\\\/53fba112c6f4f0b335578890a816262e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/#\\\/schema\\\/person\\\/53fba112c6f4f0b335578890a816262e\",\"name\":\"Loriental\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2015\\\/02\\\/cropped-bannier_altaiir-enrico.jpg\",\"url\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2015\\\/02\\\/cropped-bannier_altaiir-enrico.jpg\",\"contentUrl\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2015\\\/02\\\/cropped-bannier_altaiir-enrico.jpg\",\"width\":1200,\"height\":150,\"caption\":\"Loriental\"},\"logo\":{\"@id\":\"https:\\\/\\\/enricomaciasloriental.fr\\\/WordPress\\\/wp-content\\\/uploads\\\/\\\/2015\\\/02\\\/cropped-bannier_altaiir-enrico.jpg\"},\"sameAs\":[\"http:\\\/\\\/www.enricomaciasloriental.fr\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux - ENRICO MACIAS L&#039;Oriental","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux - ENRICO MACIAS L&#039;Oriental","og_description":"Il faisait chaud, tr\u00e8s chaud ce vendredi 19 aout 2016 \u00e0 Carmaux pour l\u2019ouverture de la F\u00eate de St Privat. Mais les Carmausins se sont \u00e9vertu\u00e9s toute la journ\u00e9e \u00e0 peaufiner les derniers d\u00e9tails &hellip; Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux Read more \u2192","og_url":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/","og_site_name":"ENRICO MACIAS L&#039;Oriental","article_published_time":"2016-08-21T08:46:43+00:00","article_modified_time":"2016-08-21T08:48:18+00:00","og_image":[{"url":"http:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2016\/08\/Carmaux-8344-1-300x200.jpg","type":"","width":"","height":""}],"author":"Loriental","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Loriental","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/#article","isPartOf":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/"},"author":{"name":"Loriental","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#\/schema\/person\/53fba112c6f4f0b335578890a816262e"},"headline":"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux","datePublished":"2016-08-21T08:46:43+00:00","dateModified":"2016-08-21T08:48:18+00:00","mainEntityOfPage":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/"},"wordCount":532,"commentCount":0,"publisher":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#\/schema\/person\/53fba112c6f4f0b335578890a816262e"},"image":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/#primaryimage"},"thumbnailUrl":"http:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2016\/08\/Carmaux-8344-1-300x200.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/","url":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/","name":"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux - ENRICO MACIAS L&#039;Oriental","isPartOf":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/#primaryimage"},"image":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/#primaryimage"},"thumbnailUrl":"http:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2016\/08\/Carmaux-8344-1-300x200.jpg","datePublished":"2016-08-21T08:46:43+00:00","dateModified":"2016-08-21T08:48:18+00:00","breadcrumb":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/#primaryimage","url":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2016\/08\/Carmaux-8344-1.jpg","contentUrl":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2016\/08\/Carmaux-8344-1.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/enricomaciasloriental.fr\/WordPress\/"},{"@type":"ListItem","position":2,"name":"Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux"}]},{"@type":"WebSite","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#website","url":"https:\/\/enricomaciasloriental.fr\/WordPress\/","name":"ENRICO MACIAS L'Oriental","description":"IL EST COMME LE SOLEIL","publisher":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#\/schema\/person\/53fba112c6f4f0b335578890a816262e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enricomaciasloriental.fr\/WordPress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/#\/schema\/person\/53fba112c6f4f0b335578890a816262e","name":"Loriental","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2015\/02\/cropped-bannier_altaiir-enrico.jpg","url":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2015\/02\/cropped-bannier_altaiir-enrico.jpg","contentUrl":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2015\/02\/cropped-bannier_altaiir-enrico.jpg","width":1200,"height":150,"caption":"Loriental"},"logo":{"@id":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-content\/uploads\/\/2015\/02\/cropped-bannier_altaiir-enrico.jpg"},"sameAs":["http:\/\/www.enricomaciasloriental.fr\/"]}]}},"featured_image_src":"","featured_image_src_square":false,"author_info":{"display_name":"Loriental","author_link":"https:\/\/enricomaciasloriental.fr\/WordPress\/author\/admin9234\/"},"rbea_author_info":{"display_name":"Loriental","author_link":"https:\/\/enricomaciasloriental.fr\/WordPress\/author\/admin9234\/"},"rbea_excerpt_info":"Il faisait chaud, tr\u00e8s chaud ce vendredi 19 aout 2016 \u00e0 Carmaux pour l\u2019ouverture de la F\u00eate de St Privat. Mais les Carmausins se sont \u00e9vertu\u00e9s toute la journ\u00e9e \u00e0 peaufiner les derniers d\u00e9tails &hellip;<p class=\"read-more\"> <a class=\"more-link\" href=\"https:\/\/enricomaciasloriental.fr\/WordPress\/enrico-macias-a-la-fete-de-st-privat-a-carmaux\/\"> <span class=\"screen-reader-text\">Enrico Macias \u00e0 la f\u00eate de St Privat \u00e0 Carmaux<\/span> Read more \u2192<\/a><\/p>","category_list":"<a href=\"https:\/\/enricomaciasloriental.fr\/WordPress\/category\/actualites\/\">Actualit\u00e9s<\/a>","comments_num":"0 comments","_links":{"self":[{"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/posts\/9883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/comments?post=9883"}],"version-history":[{"count":0,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/posts\/9883\/revisions"}],"wp:attachment":[{"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/media?parent=9883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/categories?post=9883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enricomaciasloriental.fr\/WordPress\/wp-json\/wp\/v2\/tags?post=9883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}